{"id":775,"date":"2022-09-23T07:49:15","date_gmt":"2022-09-23T07:49:15","guid":{"rendered":"https:\/\/fedic.it\/magazine\/?p=775"},"modified":"2022-09-23T07:49:15","modified_gmt":"2022-09-23T07:49:15","slug":"salotto-fedic-al-22-corto-fiction-di-chianciano","status":"publish","type":"post","link":"https:\/\/fedic.it\/magazine\/salotto-fedic-al-22-corto-fiction-di-chianciano\/","title":{"rendered":"SALOTTO FEDIC AL 22. CORTO FICTION DI CHIANCIANO"},"content":{"rendered":"<p><strong>di Cristiana Marcocci<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: right;\"><strong>Passeggiere: &#8230;<\/strong>Quella vita ch\u2019\u00e8 una cosa bella,<br \/>\nnon \u00e8 la vita che si conosce,<br \/>\nma quella che non si conosce;<br \/>\nnon la vita passata, ma la futura.<br \/>\nColl\u2019 anno nuovo,<br \/>\nil caso incomincer\u00e0 a trattar bene<br \/>\nvoi e me e tutti gli altri,<br \/>\ne si principier\u00e0 la vita felice.<br \/>\nNon \u00e8 vero?<br \/>\n<strong>Venditore: <\/strong>Speriamo.<br \/>\n<strong><em>G. Leopardi<\/em><\/strong><\/p>\n<p><strong><em>\u00a0<\/em><\/strong><\/p>\n<p><strong><em>\u00a0<\/em><\/strong><\/p>\n<figure id=\"attachment_752\" aria-describedby=\"caption-attachment-752\" style=\"width: 208px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-752 size-medium\" src=\"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2022\/09\/Cristiana-Marcocci-208x300.png\" alt=\"\" width=\"208\" height=\"300\" srcset=\"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2022\/09\/Cristiana-Marcocci-208x300.png 208w, https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2022\/09\/Cristiana-Marcocci.png 412w\" sizes=\"auto, (max-width: 208px) 100vw, 208px\" \/><figcaption id=\"caption-attachment-752\" class=\"wp-caption-text\">Cristiana Marcocci<\/figcaption><\/figure>\n<p>Venerd\u00ec 19 e sabato 20 agosto 2022 si \u00e8 svolto a Chianciano il 22\u00b0Corto Fiction, uno dei pi\u00f9 longevi fra i festival dedicati ai cortometraggi in Italia.<br \/>\nIl sabato mattina ha avuto luogo il tradizionale incontro del Salotto FEDIC, un\u2019occasione preziosa per ripercorrere la storia e dare informazioni sulle attivit\u00e0 dei cineclub italiani.<br \/>\nQuest\u2019anno ci ha accolto una location eccezionale, il Parco Acquasanta delle Terme di Chianciano, dove sotto un albero secolare e sullo sfondo della Sala Fellini, evocativo luogo delle proiezioni, un gruppo di persone addette ai lavori e accomunate dall\u2019interesse per il cinema hanno trascorso un paio di piacevoli e fruttuose ore insieme.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-751\" src=\"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2022\/09\/6.png\" alt=\"\" width=\"1004\" height=\"589\" srcset=\"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2022\/09\/6.png 1004w, https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2022\/09\/6-300x176.png 300w, https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2022\/09\/6-768x451.png 768w\" sizes=\"auto, (max-width: 1004px) 100vw, 1004px\" \/><\/p>\n<p>Ha aperto l\u2019incontro Giorgio Ricci, attualmente Presidente del Cineclub \u201cPandolfi\u201d di Pesaro, che ha rivestito negli anni importanti incarichi dirigenziali in ambito FEDIC. Ha ripercorso con noi la storia della creazione dell\u2019Archivio Nazionale Cinema d\u2019Impresa di Ivrea. Grazie alla passione e l\u2019impegno di chi negli anni ha voluto e creduto nella realizzazione di questo progetto adesso \u00e8 possibile a tutti, non solo ricercatori, insegnanti o studenti ma anche curiosi o appassionati di avere a disposizione, a richiesta e al solo scopo di diffondere cultura, un numero elevatissimo di film e cortometraggi. La Cineteca FEDIC \u00e8 attualmente curata da un Comitato scientifico presieduto da Paolo Micalizzi e composto da Laura Biggi, Lorenzo Caravello, Gianluca Castellini e Marco Rosati.<br \/>\nFra i tanti cortometraggi a disposizione \u00e8 stato citato \u201cIl dialogo fra un venditore di almanacchi e un passeggiere\u201d tratto dall\u2019omonimo dialogo di Giacomo Leopardi e diretto da Ermanno Olmi nel 1954.<br \/>\nSuccessivamente Roberto Merlino, direttore artistico di Corte Tripoli Cinematografica, direttore dello Stage Nazionale, insegnante che ha rivestito importanti incarichi dirigenziali in ambito FEDIC, ha illustrato il 18\u00b0 Stage nazionale FEDIC in programma a Calci (Pi) presso l\u2019agriturismo \u201cI Felloni\u201d dal 25 al 29 agosto 2022. Si tratta di un percorso ludico- formativo, adatto sia a persone esperte sia a principianti che porter\u00e0 alla realizzazione di soggetto e sceneggiatura di quattro diversi cortometraggi.\u00a0 Per un costo pi\u00f9 che accessibile, 400 euro tutto compreso (vitto, alloggio e materiali). I partecipanti godranno di un\u2019esperienza unica, all\u2019insegna del divertimento e dello scambio di esperienze, apprendendo o approfondendo le loro conoscenze grazie a insegnanti esperti e qualificati.<br \/>\nErano presenti all\u2019incontro due giovani autori, Daniele Esposito e Antonella Calabrese, anche bravissima attrice, che risulteranno, nel pomeriggio, vincitori del premio del pubblico con il loro eccellente \u201cVenti minuti\u201d e che ci hanno raccontato di quanto, attualmente, in questo campo, si dia importanza pi\u00f9 alla tecnica che al contenuto: il prodotto deve essere \u201ccatchy\u201d, accattivante e alla moda. Pare, ormai, quasi impossibile dare spazio alla propria creativit\u00e0 senza una scuola e una produzione importante alle spalle.<\/p>\n<p>Su questo tema si sono inseriti gli organizzatori del Festival Lauro Crociani e Cristiana Vitalesta che hanno sottolineato come, da sempre, il Festival Corto Fiction abbia fatto scelte non in base alla tecnica o ai nomi di richiamo ma alle idee e ai contenuti. La selezione viene fatta di comune accordo dal direttivo, composto da appassionati di cinema, che spesso sono anche, a loro volta, autori, registi e attori. Hanno ricordato, a tal proposito, un cortometraggio, poi premiato, che era stato girato abilmente con un cellulare.\u00a0 Quest\u2019anno al Festival sono arrivate 207 opere per un totale di quarantatr\u00e9 ore di materiale di cui quattro sono state trasmesse in sala.<\/p>\n<p>\u00c8 arrivato il tempo dei saluti, non senza prima aver ancora una volta ribadito la qualit\u00e0 di questo Festival che, da ormai 22 anni, premia il valore dei messaggi e d\u00e0 spazio a tutte le voci che lo meritano.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>di Cristiana Marcocci \u00a0 Passeggiere: &#8230;Quella vita ch\u2019\u00e8 una cosa bella, non \u00e8 la vita che si conosce, ma quella che non si conosce; non la vita passata, ma la futura. Coll\u2019 anno nuovo, il caso incomincer\u00e0 a trattar bene voi e me e tutti gli altri, e si principier\u00e0 la vita felice. Non \u00e8 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":752,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,4],"tags":[24],"class_list":["post-775","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fedic","category-festival","tag-fedic-magazine-36"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SALOTTO FEDIC AL 22. CORTO FICTION DI CHIANCIANO - Fedic Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fedic.it\/magazine\/salotto-fedic-al-22-corto-fiction-di-chianciano\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SALOTTO FEDIC AL 22. CORTO FICTION DI CHIANCIANO - Fedic Magazine\" \/>\n<meta property=\"og:description\" content=\"di Cristiana Marcocci \u00a0 Passeggiere: &#8230;Quella vita ch\u2019\u00e8 una cosa bella, non \u00e8 la vita che si conosce, ma quella che non si conosce; non la vita passata, ma la futura. Coll\u2019 anno nuovo, il caso incomincer\u00e0 a trattar bene voi e me e tutti gli altri, e si principier\u00e0 la vita felice. Non \u00e8 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fedic.it\/magazine\/salotto-fedic-al-22-corto-fiction-di-chianciano\/\" \/>\n<meta property=\"og:site_name\" content=\"Fedic Magazine\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-23T07:49:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2022\/09\/Cristiana-Marcocci.png\" \/>\n\t<meta property=\"og:image:width\" content=\"412\" \/>\n\t<meta property=\"og:image:height\" content=\"593\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/salotto-fedic-al-22-corto-fiction-di-chianciano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/salotto-fedic-al-22-corto-fiction-di-chianciano\\\/\"},\"author\":{\"name\":\"redazione\",\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/#\\\/schema\\\/person\\\/49d2a224aa980c875e12fa73c5601332\"},\"headline\":\"SALOTTO FEDIC AL 22. CORTO FICTION DI CHIANCIANO\",\"datePublished\":\"2022-09-23T07:49:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/salotto-fedic-al-22-corto-fiction-di-chianciano\\\/\"},\"wordCount\":660,\"publisher\":{\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/salotto-fedic-al-22-corto-fiction-di-chianciano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Cristiana-Marcocci.png\",\"keywords\":[\"FEDIC Magazine 36\"],\"articleSection\":[\"Fedic\",\"Festival\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/salotto-fedic-al-22-corto-fiction-di-chianciano\\\/\",\"url\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/salotto-fedic-al-22-corto-fiction-di-chianciano\\\/\",\"name\":\"SALOTTO FEDIC AL 22. CORTO FICTION DI CHIANCIANO - Fedic Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/salotto-fedic-al-22-corto-fiction-di-chianciano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/salotto-fedic-al-22-corto-fiction-di-chianciano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Cristiana-Marcocci.png\",\"datePublished\":\"2022-09-23T07:49:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/salotto-fedic-al-22-corto-fiction-di-chianciano\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fedic.it\\\/magazine\\\/salotto-fedic-al-22-corto-fiction-di-chianciano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/salotto-fedic-al-22-corto-fiction-di-chianciano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Cristiana-Marcocci.png\",\"contentUrl\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Cristiana-Marcocci.png\",\"width\":412,\"height\":593,\"caption\":\"Cristiana Marcocci\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/salotto-fedic-al-22-corto-fiction-di-chianciano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SALOTTO FEDIC AL 22. CORTO FICTION DI CHIANCIANO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/#website\",\"url\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/\",\"name\":\"Fedic Magazine\",\"description\":\"Il blog della Federazione Italiana dei Cineclub\",\"publisher\":{\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/#organization\",\"name\":\"Fedic Magazine\",\"url\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo-fedic-magazine-ok.jpg\",\"contentUrl\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo-fedic-magazine-ok.jpg\",\"width\":405,\"height\":110,\"caption\":\"Fedic Magazine\"},\"image\":{\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/#\\\/schema\\\/person\\\/49d2a224aa980c875e12fa73c5601332\",\"name\":\"redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3df0bdaff167c479390d8c1d9ba8338511cc6ea40b290cd3d84683663005fd1c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3df0bdaff167c479390d8c1d9ba8338511cc6ea40b290cd3d84683663005fd1c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3df0bdaff167c479390d8c1d9ba8338511cc6ea40b290cd3d84683663005fd1c?s=96&d=mm&r=g\",\"caption\":\"redazione\"},\"url\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SALOTTO FEDIC AL 22. CORTO FICTION DI CHIANCIANO - Fedic Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fedic.it\/magazine\/salotto-fedic-al-22-corto-fiction-di-chianciano\/","og_locale":"it_IT","og_type":"article","og_title":"SALOTTO FEDIC AL 22. CORTO FICTION DI CHIANCIANO - Fedic Magazine","og_description":"di Cristiana Marcocci \u00a0 Passeggiere: &#8230;Quella vita ch\u2019\u00e8 una cosa bella, non \u00e8 la vita che si conosce, ma quella che non si conosce; non la vita passata, ma la futura. Coll\u2019 anno nuovo, il caso incomincer\u00e0 a trattar bene voi e me e tutti gli altri, e si principier\u00e0 la vita felice. Non \u00e8 [&hellip;]","og_url":"https:\/\/fedic.it\/magazine\/salotto-fedic-al-22-corto-fiction-di-chianciano\/","og_site_name":"Fedic Magazine","article_published_time":"2022-09-23T07:49:15+00:00","og_image":[{"width":412,"height":593,"url":"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2022\/09\/Cristiana-Marcocci.png","type":"image\/png"}],"author":"redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fedic.it\/magazine\/salotto-fedic-al-22-corto-fiction-di-chianciano\/#article","isPartOf":{"@id":"https:\/\/fedic.it\/magazine\/salotto-fedic-al-22-corto-fiction-di-chianciano\/"},"author":{"name":"redazione","@id":"https:\/\/fedic.it\/magazine\/#\/schema\/person\/49d2a224aa980c875e12fa73c5601332"},"headline":"SALOTTO FEDIC AL 22. CORTO FICTION DI CHIANCIANO","datePublished":"2022-09-23T07:49:15+00:00","mainEntityOfPage":{"@id":"https:\/\/fedic.it\/magazine\/salotto-fedic-al-22-corto-fiction-di-chianciano\/"},"wordCount":660,"publisher":{"@id":"https:\/\/fedic.it\/magazine\/#organization"},"image":{"@id":"https:\/\/fedic.it\/magazine\/salotto-fedic-al-22-corto-fiction-di-chianciano\/#primaryimage"},"thumbnailUrl":"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2022\/09\/Cristiana-Marcocci.png","keywords":["FEDIC Magazine 36"],"articleSection":["Fedic","Festival"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/fedic.it\/magazine\/salotto-fedic-al-22-corto-fiction-di-chianciano\/","url":"https:\/\/fedic.it\/magazine\/salotto-fedic-al-22-corto-fiction-di-chianciano\/","name":"SALOTTO FEDIC AL 22. CORTO FICTION DI CHIANCIANO - Fedic Magazine","isPartOf":{"@id":"https:\/\/fedic.it\/magazine\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fedic.it\/magazine\/salotto-fedic-al-22-corto-fiction-di-chianciano\/#primaryimage"},"image":{"@id":"https:\/\/fedic.it\/magazine\/salotto-fedic-al-22-corto-fiction-di-chianciano\/#primaryimage"},"thumbnailUrl":"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2022\/09\/Cristiana-Marcocci.png","datePublished":"2022-09-23T07:49:15+00:00","breadcrumb":{"@id":"https:\/\/fedic.it\/magazine\/salotto-fedic-al-22-corto-fiction-di-chianciano\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fedic.it\/magazine\/salotto-fedic-al-22-corto-fiction-di-chianciano\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/fedic.it\/magazine\/salotto-fedic-al-22-corto-fiction-di-chianciano\/#primaryimage","url":"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2022\/09\/Cristiana-Marcocci.png","contentUrl":"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2022\/09\/Cristiana-Marcocci.png","width":412,"height":593,"caption":"Cristiana Marcocci"},{"@type":"BreadcrumbList","@id":"https:\/\/fedic.it\/magazine\/salotto-fedic-al-22-corto-fiction-di-chianciano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fedic.it\/magazine\/"},{"@type":"ListItem","position":2,"name":"SALOTTO FEDIC AL 22. CORTO FICTION DI CHIANCIANO"}]},{"@type":"WebSite","@id":"https:\/\/fedic.it\/magazine\/#website","url":"https:\/\/fedic.it\/magazine\/","name":"Fedic Magazine","description":"Il blog della Federazione Italiana dei Cineclub","publisher":{"@id":"https:\/\/fedic.it\/magazine\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fedic.it\/magazine\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/fedic.it\/magazine\/#organization","name":"Fedic Magazine","url":"https:\/\/fedic.it\/magazine\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/fedic.it\/magazine\/#\/schema\/logo\/image\/","url":"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2021\/07\/logo-fedic-magazine-ok.jpg","contentUrl":"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2021\/07\/logo-fedic-magazine-ok.jpg","width":405,"height":110,"caption":"Fedic Magazine"},"image":{"@id":"https:\/\/fedic.it\/magazine\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/fedic.it\/magazine\/#\/schema\/person\/49d2a224aa980c875e12fa73c5601332","name":"redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/3df0bdaff167c479390d8c1d9ba8338511cc6ea40b290cd3d84683663005fd1c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3df0bdaff167c479390d8c1d9ba8338511cc6ea40b290cd3d84683663005fd1c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3df0bdaff167c479390d8c1d9ba8338511cc6ea40b290cd3d84683663005fd1c?s=96&d=mm&r=g","caption":"redazione"},"url":"https:\/\/fedic.it\/magazine\/author\/redazione\/"}]}},"jetpack_featured_media_url":"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2022\/09\/Cristiana-Marcocci.png","_links":{"self":[{"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/posts\/775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/comments?post=775"}],"version-history":[{"count":1,"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/posts\/775\/revisions"}],"predecessor-version":[{"id":776,"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/posts\/775\/revisions\/776"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/media\/752"}],"wp:attachment":[{"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/media?parent=775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/categories?post=775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/tags?post=775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}