{"id":646,"date":"2022-07-26T11:56:04","date_gmt":"2022-07-26T11:56:04","guid":{"rendered":"https:\/\/fedic.it\/magazine\/?p=646"},"modified":"2022-07-26T13:45:38","modified_gmt":"2022-07-26T13:45:38","slug":"esistenze-in-bilico-i-film-di-fedic-reff","status":"publish","type":"post","link":"https:\/\/fedic.it\/magazine\/esistenze-in-bilico-i-film-di-fedic-reff\/","title":{"rendered":"ESISTENZE IN BILICO \u2013 I Film di FEDIC REFF"},"content":{"rendered":"<p><strong>di Marcello Cella<\/strong><\/p>\n<p>Se c\u2019\u00e8 un\u2019immagine in grado di sintetizzare emotivamente e culturalmente la selezione di quest\u2019anno di Fedic Reff presentata all\u2019interno del Festival Cinematografico di Montecatini \u00e8 quella della mamma orsa polare di \u201cMigrants\u201d che con il suo piccolo va alla deriva nell\u2019oceano su una zattera di ghiaccio che si \u00e8 staccata dal resto del ghiacciaio a causa del riscaldamento globale. Infatti tutti i film del Fedic Reff di quest\u2019anno raccontano storie di un\u2019umanit\u00e0 in bilico fra personali percorsi di sopravvivenza in un mondo sempre pi\u00f9 incomprensibile e alla deriva di valori e obiettivi materiali. Come se, nonostante la diversa provenienza geografica delle opere, esistesse sottotraccia un identico fiume carsico emotivo che porta gli autori a riflettere sul significato della propria esistenza in un mondo dominato dai disvalori etici e materiali del tardo capitalismo occidentale.<br \/>\nE\u2019 il caso del film sudanese \u201cAl-Sit\u201d di Suzannah Mirghani che racconta la storia di un gruppo di ragazzini che vive in una poverissima periferia cittadina, alle prese con i quotidiani stratagemmi per sbarcare il lunario.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-641\" src=\"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2022\/07\/foto-1.png\" alt=\"\" width=\"514\" height=\"320\" srcset=\"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2022\/07\/foto-1.png 514w, https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2022\/07\/foto-1-300x187.png 300w\" sizes=\"auto, (max-width: 514px) 100vw, 514px\" \/><\/p>\n<p>Uno dei quali consiste nel raccogliere rame e altri metalli per scambiarli con i film in dvd che un venditore ambulante utilizza come moneta di scambio. I film, horror soprattutto, sono l\u2019unico mezzo per evadere da una realt\u00e0 sociale che lascia ben poco spazio alla speranza. Finch\u00e9 un giorno i ragazzini mettono l\u2019occhio su un vecchio proiettore in pellicola che il venditore ambulante tiene nel suo furgone. E\u2019 un bell\u2019oggetto che affascina i ragazzi, i quali, raccolti i soldi con una fortunosa colletta, riescono ad affittare per vedere finalmente un film in pellicola, un film vero. Purtroppo il venditore ne ha solo uno, \u201cNuovo Cinema Paradiso\u201d di Giuseppe Tornatore, che i ragazzi non conoscono, ma di cui si innamorano, identificandosi nel piccolo protagonista della pellicola, cos\u00ec lontano da loro, ma in fondo cos\u00ec vicino. Bella metafora sociale sulla forza eterna del cinema.<\/p>\n<p>Un\u2019adolescente \u00e8 anche la protagonista del film olandese \u201cStolen kisses\u201d di Lidi Toepoel, premiato a Montecatini dalla Giuria Giovani. Amy va tutti i giorni a trovare la nonna che vive in una casa di riposo e gioca a carte con lei barando un po\u2019 per ricevere doppia paghetta, sfruttando le capacit\u00e0 mnemoniche sempre pi\u00f9 labili dell\u2019anziana signora. Una innocente marachella che consente alla ragazzina di mettere insieme un piccolo gruzzoletto per le sue spese. Ma un giorno Runin, l\u2019anziano signore di cui la nonna si \u00e8 invaghita e con cui passa le sue giornate, viene spostato dai suoi familiari in un\u2019altra casa di riposo, spezzando senza tanti complimenti il dolce idillio fra i due vecchietti. Colpita dalla tristezza della nonna, Amy decide di investire il suo gruzzoletto per farle incontrare di nuovo Runin. Un gesto dolcissimo che dar\u00e0 un momento di felicit\u00e0 alla nonna, anche se non potr\u00e0 cambiare l\u2019inesorabile passare del tempo e le sue conseguenze. Opera di grande intensit\u00e0 emotiva, sostenuta da una prova attoriale straordinaria della giovane protagonista.<\/p>\n<p>Ancora un adolescente \u00e8 il protagonista del norvegese \u201cPopocorngutten\u201d, favola nera e surreale, ma non troppo, che racconta la storia di Tom, un ragazzino che scopre di avere una dote bizzarra: quella di produrre pop corn ogni volta che starnutisce. E\u2019 una cosa giocosa e divertente, ma un bieco uomo d\u2019affari in bancarotta ne trae l\u2019idea per tirarsi fuori dai guai finanziari sfruttando le bizzarre capacit\u00e0 di Tom nel produrre pop corn a costo zero. Compra il ragazzino dalla sua famiglia e, fedele alle regole del capitalismo pi\u00f9 sfrenato, lo spreme fino allo stremo finch\u00e9 il ragazzino smette di produrre i pop corn e forse riesce a liberarsi dal suo feroce aguzzino. Anche se forse qualche altro ragazzino prender\u00e0 il suo posto in un altro paese lontano\u2026 Amara parabola sulle nefandezze del turbo capitalismo. A cui si ricollega in fondo anche il gi\u00e0 citato \u201cMigrants\u201d, bellissimo cortometraggio d\u2019animazione francese di cinque autori giovanissimi, Caby, Devise, Dupriez, Kubiak, Lermytte. A causa del riscaldamento globale mamma orsa e il suo piccolo, rimangono prigionieri su una lastra di ghiaccio alla deriva che, attraversando l\u2019oceano, li porta in un paese lontanissimo dal loro, abitato da una trib\u00f9 di orsi bruni per niente contenti di avere dei nuovi vicini. Da questo momento nasceranno conflitti e relazioni drammatiche o esilaranti fra i due orsi polari e i loro nuovi ospiti con cui dovranno imparare a convivere e a condividere le risorse disponibili nella foresta fino alla necessit\u00e0 di una nuova partenza a cui mamma orsa non sopravviver\u00e0. Mentre il piccolo orsacchiotto, naufrago sulla spiaggia, scambiato per un pupazzo di pezza, verr\u00e0 portato via da una mano bambina. Metafora delicata e intelligente che unisce in un\u2019unica riflessione il problema del riscaldamento globale con quello delle migrazioni, spesso causate proprio dalla crisi climatica, utilizzando con bella disinvoltura il linguaggio dell\u2019animazione con i due orsi polari protagonisti, pieni di toppe e cuciture come se fossero fatti di materiale riciclato.<\/p>\n<p>Infine, lo spagnolo \u201cLa Banyera\u201d di Sergj Mart\u00ec i Maltas, non pu\u00f2 che riportare alla nostra memoria la frase cult di una celebre pubblicit\u00e0 di un telefono: \u201cUna telefonata allunga la vita\u201d.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-642\" src=\"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2022\/07\/foto-2.png\" alt=\"\" width=\"531\" height=\"312\" srcset=\"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2022\/07\/foto-2.png 531w, https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2022\/07\/foto-2-300x176.png 300w\" sizes=\"auto, (max-width: 531px) 100vw, 531px\" \/><\/p>\n<p>E\u2019 proprio il caso del protagonista Ramon che, mentre assapora gli ultimi minuti del suo suicidio preparato con meticolosit\u00e0 nella sua vasca da bagno, viene interrotto nel suo proposito mortale dalla telefonata di una ragazza che pubblicizza una assicurazione sulla vita. Dapprima infuriato, Ramon rifiuta ogni discussione, ma davanti all\u2019ostinazione della ragazza e al racconto struggente della sua storia di lavoratrice precaria e di aspirante scrittrice, si incuriosisce sempre pi\u00f9 fino a desistere dal suo proposito iniziale. E forse acquister\u00e0 anche una polizza sulla vita. Il tono da commedia svitata, un po\u2019 alla Almodovar, non lascia passare per\u00f2 in secondo piano la riflessione sulla solitudine degli esseri umani nel nostro mondo cos\u00ec interconnesso, cos\u00ec social e in realt\u00e0 cos\u00ec fragile.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>di Marcello Cella Se c\u2019\u00e8 un\u2019immagine in grado di sintetizzare emotivamente e culturalmente la selezione di quest\u2019anno di Fedic Reff presentata all\u2019interno del Festival Cinematografico di Montecatini \u00e8 quella della mamma orsa polare di \u201cMigrants\u201d che con il suo piccolo va alla deriva nell\u2019oceano su una zattera di ghiaccio che si \u00e8 staccata dal resto [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[22],"class_list":["post-646","post","type-post","status-publish","format-standard","hentry","category-festival","tag-fedic-magazine-34-1"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ESISTENZE IN BILICO \u2013 I Film di FEDIC REFF - Fedic Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fedic.it\/magazine\/esistenze-in-bilico-i-film-di-fedic-reff\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ESISTENZE IN BILICO \u2013 I Film di FEDIC REFF - Fedic Magazine\" \/>\n<meta property=\"og:description\" content=\"di Marcello Cella Se c\u2019\u00e8 un\u2019immagine in grado di sintetizzare emotivamente e culturalmente la selezione di quest\u2019anno di Fedic Reff presentata all\u2019interno del Festival Cinematografico di Montecatini \u00e8 quella della mamma orsa polare di \u201cMigrants\u201d che con il suo piccolo va alla deriva nell\u2019oceano su una zattera di ghiaccio che si \u00e8 staccata dal resto [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fedic.it\/magazine\/esistenze-in-bilico-i-film-di-fedic-reff\/\" \/>\n<meta property=\"og:site_name\" content=\"Fedic Magazine\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-26T11:56:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-26T13:45:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2022\/07\/foto-1.png\" \/>\n<meta name=\"author\" content=\"redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/esistenze-in-bilico-i-film-di-fedic-reff\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/esistenze-in-bilico-i-film-di-fedic-reff\\\/\"},\"author\":{\"name\":\"redazione\",\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/#\\\/schema\\\/person\\\/49d2a224aa980c875e12fa73c5601332\"},\"headline\":\"ESISTENZE IN BILICO \u2013 I Film di FEDIC REFF\",\"datePublished\":\"2022-07-26T11:56:04+00:00\",\"dateModified\":\"2022-07-26T13:45:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/esistenze-in-bilico-i-film-di-fedic-reff\\\/\"},\"wordCount\":981,\"publisher\":{\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/esistenze-in-bilico-i-film-di-fedic-reff\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/foto-1.png\",\"keywords\":[\"FEDIC Magazine 34-1\"],\"articleSection\":[\"Festival\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/esistenze-in-bilico-i-film-di-fedic-reff\\\/\",\"url\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/esistenze-in-bilico-i-film-di-fedic-reff\\\/\",\"name\":\"ESISTENZE IN BILICO \u2013 I Film di FEDIC REFF - Fedic Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/esistenze-in-bilico-i-film-di-fedic-reff\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/esistenze-in-bilico-i-film-di-fedic-reff\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/foto-1.png\",\"datePublished\":\"2022-07-26T11:56:04+00:00\",\"dateModified\":\"2022-07-26T13:45:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/esistenze-in-bilico-i-film-di-fedic-reff\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fedic.it\\\/magazine\\\/esistenze-in-bilico-i-film-di-fedic-reff\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/esistenze-in-bilico-i-film-di-fedic-reff\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/foto-1.png\",\"contentUrl\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/foto-1.png\",\"width\":514,\"height\":320},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/esistenze-in-bilico-i-film-di-fedic-reff\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ESISTENZE IN BILICO \u2013 I Film di FEDIC REFF\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/#website\",\"url\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/\",\"name\":\"Fedic Magazine\",\"description\":\"Il blog della Federazione Italiana dei Cineclub\",\"publisher\":{\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/#organization\",\"name\":\"Fedic Magazine\",\"url\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo-fedic-magazine-ok.jpg\",\"contentUrl\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo-fedic-magazine-ok.jpg\",\"width\":405,\"height\":110,\"caption\":\"Fedic Magazine\"},\"image\":{\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/#\\\/schema\\\/person\\\/49d2a224aa980c875e12fa73c5601332\",\"name\":\"redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3df0bdaff167c479390d8c1d9ba8338511cc6ea40b290cd3d84683663005fd1c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3df0bdaff167c479390d8c1d9ba8338511cc6ea40b290cd3d84683663005fd1c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3df0bdaff167c479390d8c1d9ba8338511cc6ea40b290cd3d84683663005fd1c?s=96&d=mm&r=g\",\"caption\":\"redazione\"},\"url\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ESISTENZE IN BILICO \u2013 I Film di FEDIC REFF - Fedic Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fedic.it\/magazine\/esistenze-in-bilico-i-film-di-fedic-reff\/","og_locale":"it_IT","og_type":"article","og_title":"ESISTENZE IN BILICO \u2013 I Film di FEDIC REFF - Fedic Magazine","og_description":"di Marcello Cella Se c\u2019\u00e8 un\u2019immagine in grado di sintetizzare emotivamente e culturalmente la selezione di quest\u2019anno di Fedic Reff presentata all\u2019interno del Festival Cinematografico di Montecatini \u00e8 quella della mamma orsa polare di \u201cMigrants\u201d che con il suo piccolo va alla deriva nell\u2019oceano su una zattera di ghiaccio che si \u00e8 staccata dal resto [&hellip;]","og_url":"https:\/\/fedic.it\/magazine\/esistenze-in-bilico-i-film-di-fedic-reff\/","og_site_name":"Fedic Magazine","article_published_time":"2022-07-26T11:56:04+00:00","article_modified_time":"2022-07-26T13:45:38+00:00","og_image":[{"url":"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2022\/07\/foto-1.png","type":"","width":"","height":""}],"author":"redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"redazione","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fedic.it\/magazine\/esistenze-in-bilico-i-film-di-fedic-reff\/#article","isPartOf":{"@id":"https:\/\/fedic.it\/magazine\/esistenze-in-bilico-i-film-di-fedic-reff\/"},"author":{"name":"redazione","@id":"https:\/\/fedic.it\/magazine\/#\/schema\/person\/49d2a224aa980c875e12fa73c5601332"},"headline":"ESISTENZE IN BILICO \u2013 I Film di FEDIC REFF","datePublished":"2022-07-26T11:56:04+00:00","dateModified":"2022-07-26T13:45:38+00:00","mainEntityOfPage":{"@id":"https:\/\/fedic.it\/magazine\/esistenze-in-bilico-i-film-di-fedic-reff\/"},"wordCount":981,"publisher":{"@id":"https:\/\/fedic.it\/magazine\/#organization"},"image":{"@id":"https:\/\/fedic.it\/magazine\/esistenze-in-bilico-i-film-di-fedic-reff\/#primaryimage"},"thumbnailUrl":"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2022\/07\/foto-1.png","keywords":["FEDIC Magazine 34-1"],"articleSection":["Festival"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/fedic.it\/magazine\/esistenze-in-bilico-i-film-di-fedic-reff\/","url":"https:\/\/fedic.it\/magazine\/esistenze-in-bilico-i-film-di-fedic-reff\/","name":"ESISTENZE IN BILICO \u2013 I Film di FEDIC REFF - Fedic Magazine","isPartOf":{"@id":"https:\/\/fedic.it\/magazine\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fedic.it\/magazine\/esistenze-in-bilico-i-film-di-fedic-reff\/#primaryimage"},"image":{"@id":"https:\/\/fedic.it\/magazine\/esistenze-in-bilico-i-film-di-fedic-reff\/#primaryimage"},"thumbnailUrl":"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2022\/07\/foto-1.png","datePublished":"2022-07-26T11:56:04+00:00","dateModified":"2022-07-26T13:45:38+00:00","breadcrumb":{"@id":"https:\/\/fedic.it\/magazine\/esistenze-in-bilico-i-film-di-fedic-reff\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fedic.it\/magazine\/esistenze-in-bilico-i-film-di-fedic-reff\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/fedic.it\/magazine\/esistenze-in-bilico-i-film-di-fedic-reff\/#primaryimage","url":"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2022\/07\/foto-1.png","contentUrl":"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2022\/07\/foto-1.png","width":514,"height":320},{"@type":"BreadcrumbList","@id":"https:\/\/fedic.it\/magazine\/esistenze-in-bilico-i-film-di-fedic-reff\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fedic.it\/magazine\/"},{"@type":"ListItem","position":2,"name":"ESISTENZE IN BILICO \u2013 I Film di FEDIC REFF"}]},{"@type":"WebSite","@id":"https:\/\/fedic.it\/magazine\/#website","url":"https:\/\/fedic.it\/magazine\/","name":"Fedic Magazine","description":"Il blog della Federazione Italiana dei Cineclub","publisher":{"@id":"https:\/\/fedic.it\/magazine\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fedic.it\/magazine\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/fedic.it\/magazine\/#organization","name":"Fedic Magazine","url":"https:\/\/fedic.it\/magazine\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/fedic.it\/magazine\/#\/schema\/logo\/image\/","url":"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2021\/07\/logo-fedic-magazine-ok.jpg","contentUrl":"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2021\/07\/logo-fedic-magazine-ok.jpg","width":405,"height":110,"caption":"Fedic Magazine"},"image":{"@id":"https:\/\/fedic.it\/magazine\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/fedic.it\/magazine\/#\/schema\/person\/49d2a224aa980c875e12fa73c5601332","name":"redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/3df0bdaff167c479390d8c1d9ba8338511cc6ea40b290cd3d84683663005fd1c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3df0bdaff167c479390d8c1d9ba8338511cc6ea40b290cd3d84683663005fd1c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3df0bdaff167c479390d8c1d9ba8338511cc6ea40b290cd3d84683663005fd1c?s=96&d=mm&r=g","caption":"redazione"},"url":"https:\/\/fedic.it\/magazine\/author\/redazione\/"}]}},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/posts\/646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/comments?post=646"}],"version-history":[{"count":1,"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/posts\/646\/revisions"}],"predecessor-version":[{"id":647,"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/posts\/646\/revisions\/647"}],"wp:attachment":[{"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/media?parent=646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/categories?post=646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/tags?post=646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}