{"id":32,"date":"2021-07-21T07:02:12","date_gmt":"2021-07-21T07:02:12","guid":{"rendered":"https:\/\/fedic.it\/magazine\/?p=32"},"modified":"2021-07-21T10:13:38","modified_gmt":"2021-07-21T10:13:38","slug":"tecnica-cinematografica-zoom","status":"publish","type":"post","link":"https:\/\/fedic.it\/magazine\/tecnica-cinematografica-zoom\/","title":{"rendered":"&#8220;ZOOM&#8221;"},"content":{"rendered":"<p>a cura di Marco Rosati<\/p>\n<p>Lo <em>zoom <\/em>(letteralmente \u201c<em>ingrandimento<\/em>\u201d) \u00e8 un movimento ottico in avanti (<em>zoom in) <\/em>o indietro <em>(zoom out) <\/em>che non necessita dello spostamento fisico della cinepresa. Storicamente il suo impiego nasce per il telescopio in astronomia e successivamente per questioni militari. La sua apparizione in ambito creativo per fotocamere risale al 1959. In analogico \u00e8 un movimento di lenti, mentre in digitale \u00e8 un ingrandimento dell\u2019immagine elaborata dalla videocamera.\u00a0 A differenza di un c<em>arrello<\/em> che muove la cinepresa lasciando lo spazio uniforme, lo zoom crea un cambiamento prospettico irreale per l\u2019abitudine dell\u2019occhio umano. Questo movimento, al pari di un carrello, crea una perdita della <em>messa a fuoco <\/em>e necessita di un aggiustamento sulla variazione della distanza dal soggetto.<\/p>\n<p><em>Martin Scorsese <\/em>ammette di avere una predilezione per questa tecnica senza nasconderne l\u2019utilizzo e nutre un fastidio notando l\u2019abuso che altri ne fanno, ponendo buon esempio l\u2019utilizzo che ne fece magistralmente <em>Mario Bava<\/em>. <em>\u00a0<\/em>Nel cinema \u00e8 stato adoperato per dare continuit\u00e0 di visione senza stacco di montaggio, passando quindi da un tipo di inquadratura (stretta o larga) ad un altro senza fermare la ripresa. Un altro utilizzo \u00e8 di porre l\u2019attenzione ad uno stato d\u2019animo o ad un qualcosa presente nell\u2019inquadratura, lasciando proseguire la scena eliminando lo stacco in montaggio (o l\u2019utilizzo dell\u2019<em>occhio di bue <\/em>che in certi casi nel cinema degli albori formava un cerchio intorno ad un particolare o dettaglio importante). Racconta <em>Sydney Pollack <\/em>che per girare <em>\u201cThe firm\u201d (1993) <\/em>ha voluto scene con inquadrature in movimento e con zoom per aumentare il malessere ed instabilit\u00e0 necessari alla storia, rimarcando l\u2019importanza di tecnicismi motivati. <em>Woody Allen<\/em> dice di usare lo zoom per non tagliare le scene cos\u00ec da poter stringere su un viso per avere un primo piano o tornare su campo lungo, svolgendo cos\u00ec maggior parte di montaggio sul set anzich\u00e9 in sala. Contrario era <em>Wim Wenders<\/em>, che si diceva addirittura terrorizzato dall\u2019utilizzo dello zoom, ma fu lavorando sul set con <em>Michelangelo Antonioni che <\/em>cambi\u00f2 idea capendo l\u2019ottimo uso che se ne poteva fare.<\/p>\n<p>Unito ad un movimento di carrello e ad una panoramica, lo zoom non viene percepito ed il taglio dell\u2019inquadratura varia di profondit\u00e0 (vedi \u201c<em>Prova D\u2019Orchestra\u201d \u2013 Federico Fellini, 1979<\/em>). Ma al di l\u00e0 di una continuit\u00e0 ed un piacere visivo, lo zoom pu\u00f2 essere sottolineatura di uno stato d\u2019animo, come accade in <em>\u201cAccattone\u201d (Pier Paolo Pasolini, 1961),<\/em> creando interesse sul personaggio inquadrato, dove lo zoom interviene per indicare allo spettatore un cambio d\u2019umore del personaggio sul quale viene posta l\u2019attenzione.<\/p>\n<p><em>Brian De Palma<\/em> ha adoperato molto spesso lo zoom nelle sue opere (vedi ad esempio \u201c<em>Carrie\u201d, 1976). <\/em>Nel suo \u201c<em>Domino\u201d (2019)<\/em> utilizza ad inizio film un lento \u201c<em>zoom in\u201d<\/em> durante il dialogo fra i due personaggi: mentre loro parlano l\u2019inquadratura\u00a0 ci accompagna lentamente a mostrarci sul tavolo la pistola dimenticata, che pi\u00f9 tardi sapremo quanto al protagonista\u00a0 fosse necessaria. Il lento movimento crea <em>suspance<\/em>: cosa ci sta andando a mostrare il regista? Inversamente l\u2019ingrandimento pu\u00f2 partire da un punto ed allargarsi a mostrare il contesto intorno al soggetto ripreso. Sostituisce il movimento fisico della cinepresa, dando l\u2019effetto percepibile di una compressione dell\u2019immagine. L\u2019attenzione non \u00e8 sullo spazio ma su ci\u00f2 che \u00e8 al centro dell\u2019inquadratura. E\u2019 un movimento largamente usato nel cinema casalingo, perch\u00e9 semplice, immediato ed alle prime armi divertente nel suo distorcere l\u2019immagine, permettendo di avvicinarsi senza muoversi fisicamente; effetto amatoriale che viene riproposto nel cinema per accrescere il senso di realismo ed amplificare l\u2019immedesimazione dello spettatore (vedi \u201c<em>The Big Short\u201d \u2013 Adam McKay, 2015<\/em>). E\u2019 il <em>voyerismo <\/em>per eccellenza, permettendo di spiare da lontano andando ad ingrandire un dettaglio. Usato anche per una ripresa fissa ritaglia l\u2019inquadratura in fase preparatoria senza movimento di focale durante la registrazione. Al banco di montaggio l\u2019effetto zoom pu\u00f2 essere aggiunto con programmi predisposti, spesso adoperato per creare movimento su riprese giudicate troppo statiche o su fermo immagine (vedi i titoli iniziali di \u201c<em>The Devil\u2019s Rejects\u201d \u2013 Rob Zombie, 2005)<\/em>.<\/p>\n<p>I documentari musicali che riproponevano concerti o brani con immagini di sottofondo<em>,<\/em> specialmente negli anni \u201860-\u201970, facevano spesso uso dello zoom per creare questo movimento avanti-indietro molto veloce, anche in sintonia con lo stato lisergico del periodo: vedi \u201c<em>The Velvet Underground And Nico: A Symphony Of Sound\u201d (Andy Warhol, 1966)<\/em> oppure \u201c<em>London \u201966-\u201967\u201d (Peter Whitehead, 1967).<\/em><\/p>\n<p>Chi ne ha fatto un vero e proprio stile riconoscibile \u00e8 certamente <em>Stanley Kubrick <\/em>che ha utilizzato questa tecnica specialmente per partire da un punto ed allargarsi, dando un effetto di allontanamento e di esposizione descrittiva. Pensiamo ai momenti di follia di <em>Jack Nicholson <\/em>in<em> \u201c The Shining\u201d (1980), <\/em>ma soprattutto a \u201c<em>Barry Lyndon\u201d (1975) <\/em>nell\u2019introduzione di quasi ogni cambio di scena<em>. <\/em><\/p>\n<p><em><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-33 size-full\" src=\"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2021\/07\/2-zoom.png\" alt=\"\" width=\"899\" height=\"268\" srcset=\"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2021\/07\/2-zoom.png 899w, https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2021\/07\/2-zoom-300x89.png 300w, https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2021\/07\/2-zoom-768x229.png 768w\" sizes=\"auto, (max-width: 899px) 100vw, 899px\" \/> \u00a0\u00a0 <\/em><\/p>\n<p>C\u2019\u00e8 una tecnica poi che prevede il movimento manuale della cinepresa combinato allo zoom creando una deformazione che pu\u00f2 essere usata come effetto speciale. Questa tecnica venne utilizzata da\u00a0 <em>Alfred Hitchcock<\/em> nel film \u201c<em>Vertigo\u201d (1958)<\/em> e prende il nome di <em>Dolly Zoom<\/em>, noto in Italia come <em>Effetto Vertigo.<\/em> Nel film citato \u00e8 stato usato nei momenti in cui <em>James Stewart <\/em>ha vertigine e, guardando in basso, il suolo sembra allontanarsi con il parallelo allungamento delle pareti circostanti.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-38 size-full\" src=\"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2021\/07\/zoom.png\" alt=\"\" width=\"600\" height=\"343\" srcset=\"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2021\/07\/zoom.png 600w, https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2021\/07\/zoom-300x172.png 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>L\u2019Effetto Vertigo viene impiegato in molti film horror (vedi \u201c<em>Poltergeist\u201d \u2013 Tobe Hooper, 1982)<\/em> proprio per il senso di deformazione del luogo, ma soprattutto per destabilizzare l\u2019ambiente in un momento di disorientamento o smarrimento emotivo del personaggio (vedi \u201c<em>Apollo 13\u201d \u2013 Ron Howard, 1995<\/em>). Ne fa uso <em>Martin Scorsese<\/em> in \u201c<em>Raging Bull\u201d (1980)<\/em> ed \u00e8 un trucco che viene ancora preso in considerazione anche in grandi produzioni: <em>Peter Jackson<\/em> allunga lo spazio per rendere sinistro un sentiero in \u201c<em>The Lord Of The Rings: The Fellowship Of The Ring\u201d (2001).<\/em><\/p>\n<p>Lo zoom nella sua caratteristica straniante \u00e8 stato ampliamente utilizzato nel cinema di <em>serie B<\/em>: gi\u00e0 nei titoli di testa di \u201c<em>Shaft\u201d\u00a0 (Gordon Parks, 1971) <\/em>vediamo un movimento di camera a mostrare la citt\u00e0 dall\u2019alto e poi una discesa in zoom verso la strada. Oppure nei <em>cappa e spada<\/em> dei samurai per inquadrare velocemente l\u2019espressione reattiva di un personaggio, vedi \u201c<em>Hung Hsi-Kuan\u201d (Chia-Liang Liu, 1977). <\/em>Ugualmente nel genere <em>horror <\/em>dove l\u2019esperienza di ottica innaturale pone una immediata attenzione su qualcosa <em>(\u201cThe Exorcist III\u201d \u2013 William Peter Blatty, 1990 ). <\/em>Anche nei western c\u2019\u00e8 stato un ampio utilizzo dello zoom: Sergio Leone <em>(\u201cC\u2019era Una Volta Il West\u201d, 1968) <\/em>ci ha accompagnati lentamente verso gli occhi del protagonista, contemplando l\u2019attesa di un duello.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-37\" src=\"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2021\/07\/zoom-regista.png\" alt=\"\" width=\"329\" height=\"327\" srcset=\"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2021\/07\/zoom-regista.png 329w, https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2021\/07\/zoom-regista-300x298.png 300w, https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2021\/07\/zoom-regista-150x150.png 150w, https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2021\/07\/zoom-regista-90x90.png 90w\" sizes=\"auto, (max-width: 329px) 100vw, 329px\" \/><\/p>\n<p>Immancabile poi il <em>thriller<\/em> che ne sfrutta l\u2019immediatezza d\u2019osservazione, come una spinta alle spalle dello spettatore per obbligarlo ad avvicinarsi o allontanarsi (vedi <em>\u201cProfondo Rosso\u201d \u2013 Dario Argento, 1975). <\/em>Ne ha fatto stile <em>Wes Anderson<\/em> che frequentemente lo ha utilizzato nel suo cinema <em>(<\/em>vedi \u201c<em>The Grand Budapest Hotel\u201d, 2014) <\/em>cos\u00ec come<em> Lars Von Trier<\/em> nel restituire una ripresa di approccio documentaristico per il modo in cui segue i personaggi, con scatti di zoom improvvisi che aumentano lo stato di ansia tipico dei suoi film (vedi \u201c<em>Dogville\u201d, 2003).<\/em><\/p>\n<p>E\u2019 una tecnica che \u00e8 tornata di moda nel cinema moderno nei film che calcano i generi sopra citati: <em>Quentin Tarantino <\/em>per i samurai di \u201c<em>Kill Bill:\u00a0 Volume 1\u201d (2003) <\/em>e<em> \u201cKill Bill: Volume 2\u201d (2004), <\/em>per la tensione da serie B in<em> \u201cDeath Proof\u201d (2007), <\/em>per il western di<em> \u201cDjango Unchained\u201d (2012).<\/em> Riproponendo questi generi torna efficace usarne gli stili dell\u2019epoca; \u00e8 ci\u00f2 che ha capito <em>Luca Guadagnino <\/em>girando il suo \u201c<em>Suspiria\u201d (2018) <\/em>dove lenti zoom aumentano l\u2019ansia e allo stesso tempo riportano lo spettatore alle atmosfere anni \u201970. Lo stesso ha fatto <em>Steven Spielberg <\/em>in \u201c<em>Munich\u201d (2005<\/em>) riproponendo scelte tecniche che ricordano i classici film di spionaggio. Usato con criterio, quindi, diventa una tecnica utile; in caso contrario, se abusato o sgrammaticato, diventa di cattivo gusto e controproducente, a volte mancando di logica narrativa o per palese sostituzione di un complicato carrello. Nel cinema si possono trovare invece buoni e interessanti esempi, fra i quali: <em>\u201cBlaznova Kronica\u201d (Karel Zeman, 1964), <\/em>\u201c<em>Per Qualche Dollaro In Piu\u2019\u201d (Sergio Leone, 1965), \u201cThe Graduate\u201d (Mike Nichols, 1967), \u201cEasy Rider\u201d (Dennis Hopper, 1969), \u201cI Clowns\u201d (Federico Fellini, 1970), \u201cL\u2019uccello Dalle Piume Di Cristallo\u201d (Dario Argento, 1970), \u201cA Clockwork Orange\u201d (Stanley Kubrick, 1971), \u201cLa Classe Operaia Va In Paradiso\u201d (Elio Petri, 1971), \u201cMilano Calibro 9\u201d (Fernando Di Leo, 1972), \u201cJeremiah Johnson\u201d (Sydney Pollack, 1972), \u201cPhantom Of The Paradise\u201d (Brian De Palma, 1974), \u201cNashville\u201d (Robert Altman, 1975), \u201cJaws\u201d (Steven Spielberg, 1975), \u201cAlien\u201d (Ridley Scott, 1979), \u201cNa Srebrnym Globie\u201d (Andrzej Zulawski, 1988), \u201cPulp Fiction\u201d (Quentin Tarantino, 1994), \u201cCasino\u201d (Martin Scorsese, 1995), \u201cMagnolia\u201d (Paul Thomas Anderson, 1999), \u201cShaun Of The Dead\u201d (Edgar Wright, 2005), \u201cThe Darjeeling Limited\u201d (Wes Anderson, 2007), \u201c300\u201d (Zack Snyder, 2007), \u201cThe Conjuring\u201d (James Wan, 2013), \u201cNightcrawler\u201d (Dan Gilroy, 2014). <\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>a cura di Marco Rosati Lo zoom (letteralmente \u201cingrandimento\u201d) \u00e8 un movimento ottico in avanti (zoom in) o indietro (zoom out) che non necessita dello spostamento fisico della cinepresa. Storicamente il suo impiego nasce per il telescopio in astronomia e successivamente per questioni militari. La sua apparizione in ambito creativo per fotocamere risale al 1959. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":65,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[9],"class_list":["post-32","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tecnica-cinematografica","tag-fedic-magazine-25"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;ZOOM&quot; - Fedic Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fedic.it\/magazine\/tecnica-cinematografica-zoom\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;ZOOM&quot; - Fedic Magazine\" \/>\n<meta property=\"og:description\" content=\"a cura di Marco Rosati Lo zoom (letteralmente \u201cingrandimento\u201d) \u00e8 un movimento ottico in avanti (zoom in) o indietro (zoom out) che non necessita dello spostamento fisico della cinepresa. Storicamente il suo impiego nasce per il telescopio in astronomia e successivamente per questioni militari. La sua apparizione in ambito creativo per fotocamere risale al 1959. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fedic.it\/magazine\/tecnica-cinematografica-zoom\/\" \/>\n<meta property=\"og:site_name\" content=\"Fedic Magazine\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-21T07:02:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-21T10:13:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2021\/07\/Tecnica-Cinematografica.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"470\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/tecnica-cinematografica-zoom\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/tecnica-cinematografica-zoom\\\/\"},\"author\":{\"name\":\"redazione\",\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/#\\\/schema\\\/person\\\/49d2a224aa980c875e12fa73c5601332\"},\"headline\":\"&#8220;ZOOM&#8221;\",\"datePublished\":\"2021-07-21T07:02:12+00:00\",\"dateModified\":\"2021-07-21T10:13:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/tecnica-cinematografica-zoom\\\/\"},\"wordCount\":1398,\"publisher\":{\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/tecnica-cinematografica-zoom\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Tecnica-Cinematografica.jpeg\",\"keywords\":[\"FEDIC Magazine 25\"],\"articleSection\":[\"Tecniche Cinematografiche\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/tecnica-cinematografica-zoom\\\/\",\"url\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/tecnica-cinematografica-zoom\\\/\",\"name\":\"\\\"ZOOM\\\" - Fedic Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/tecnica-cinematografica-zoom\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/tecnica-cinematografica-zoom\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Tecnica-Cinematografica.jpeg\",\"datePublished\":\"2021-07-21T07:02:12+00:00\",\"dateModified\":\"2021-07-21T10:13:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/tecnica-cinematografica-zoom\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fedic.it\\\/magazine\\\/tecnica-cinematografica-zoom\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/tecnica-cinematografica-zoom\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Tecnica-Cinematografica.jpeg\",\"contentUrl\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Tecnica-Cinematografica.jpeg\",\"width\":940,\"height\":470},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/tecnica-cinematografica-zoom\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;ZOOM&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/#website\",\"url\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/\",\"name\":\"Fedic Magazine\",\"description\":\"Il blog della Federazione Italiana dei Cineclub\",\"publisher\":{\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/#organization\",\"name\":\"Fedic Magazine\",\"url\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo-fedic-magazine-ok.jpg\",\"contentUrl\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo-fedic-magazine-ok.jpg\",\"width\":405,\"height\":110,\"caption\":\"Fedic Magazine\"},\"image\":{\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/#\\\/schema\\\/person\\\/49d2a224aa980c875e12fa73c5601332\",\"name\":\"redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3df0bdaff167c479390d8c1d9ba8338511cc6ea40b290cd3d84683663005fd1c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3df0bdaff167c479390d8c1d9ba8338511cc6ea40b290cd3d84683663005fd1c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3df0bdaff167c479390d8c1d9ba8338511cc6ea40b290cd3d84683663005fd1c?s=96&d=mm&r=g\",\"caption\":\"redazione\"},\"url\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"ZOOM\" - Fedic Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fedic.it\/magazine\/tecnica-cinematografica-zoom\/","og_locale":"it_IT","og_type":"article","og_title":"\"ZOOM\" - Fedic Magazine","og_description":"a cura di Marco Rosati Lo zoom (letteralmente \u201cingrandimento\u201d) \u00e8 un movimento ottico in avanti (zoom in) o indietro (zoom out) che non necessita dello spostamento fisico della cinepresa. Storicamente il suo impiego nasce per il telescopio in astronomia e successivamente per questioni militari. La sua apparizione in ambito creativo per fotocamere risale al 1959. [&hellip;]","og_url":"https:\/\/fedic.it\/magazine\/tecnica-cinematografica-zoom\/","og_site_name":"Fedic Magazine","article_published_time":"2021-07-21T07:02:12+00:00","article_modified_time":"2021-07-21T10:13:38+00:00","og_image":[{"width":940,"height":470,"url":"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2021\/07\/Tecnica-Cinematografica.jpeg","type":"image\/jpeg"}],"author":"redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"redazione","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fedic.it\/magazine\/tecnica-cinematografica-zoom\/#article","isPartOf":{"@id":"https:\/\/fedic.it\/magazine\/tecnica-cinematografica-zoom\/"},"author":{"name":"redazione","@id":"https:\/\/fedic.it\/magazine\/#\/schema\/person\/49d2a224aa980c875e12fa73c5601332"},"headline":"&#8220;ZOOM&#8221;","datePublished":"2021-07-21T07:02:12+00:00","dateModified":"2021-07-21T10:13:38+00:00","mainEntityOfPage":{"@id":"https:\/\/fedic.it\/magazine\/tecnica-cinematografica-zoom\/"},"wordCount":1398,"publisher":{"@id":"https:\/\/fedic.it\/magazine\/#organization"},"image":{"@id":"https:\/\/fedic.it\/magazine\/tecnica-cinematografica-zoom\/#primaryimage"},"thumbnailUrl":"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2021\/07\/Tecnica-Cinematografica.jpeg","keywords":["FEDIC Magazine 25"],"articleSection":["Tecniche Cinematografiche"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/fedic.it\/magazine\/tecnica-cinematografica-zoom\/","url":"https:\/\/fedic.it\/magazine\/tecnica-cinematografica-zoom\/","name":"\"ZOOM\" - Fedic Magazine","isPartOf":{"@id":"https:\/\/fedic.it\/magazine\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fedic.it\/magazine\/tecnica-cinematografica-zoom\/#primaryimage"},"image":{"@id":"https:\/\/fedic.it\/magazine\/tecnica-cinematografica-zoom\/#primaryimage"},"thumbnailUrl":"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2021\/07\/Tecnica-Cinematografica.jpeg","datePublished":"2021-07-21T07:02:12+00:00","dateModified":"2021-07-21T10:13:38+00:00","breadcrumb":{"@id":"https:\/\/fedic.it\/magazine\/tecnica-cinematografica-zoom\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fedic.it\/magazine\/tecnica-cinematografica-zoom\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/fedic.it\/magazine\/tecnica-cinematografica-zoom\/#primaryimage","url":"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2021\/07\/Tecnica-Cinematografica.jpeg","contentUrl":"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2021\/07\/Tecnica-Cinematografica.jpeg","width":940,"height":470},{"@type":"BreadcrumbList","@id":"https:\/\/fedic.it\/magazine\/tecnica-cinematografica-zoom\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fedic.it\/magazine\/"},{"@type":"ListItem","position":2,"name":"&#8220;ZOOM&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/fedic.it\/magazine\/#website","url":"https:\/\/fedic.it\/magazine\/","name":"Fedic Magazine","description":"Il blog della Federazione Italiana dei Cineclub","publisher":{"@id":"https:\/\/fedic.it\/magazine\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fedic.it\/magazine\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/fedic.it\/magazine\/#organization","name":"Fedic Magazine","url":"https:\/\/fedic.it\/magazine\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/fedic.it\/magazine\/#\/schema\/logo\/image\/","url":"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2021\/07\/logo-fedic-magazine-ok.jpg","contentUrl":"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2021\/07\/logo-fedic-magazine-ok.jpg","width":405,"height":110,"caption":"Fedic Magazine"},"image":{"@id":"https:\/\/fedic.it\/magazine\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/fedic.it\/magazine\/#\/schema\/person\/49d2a224aa980c875e12fa73c5601332","name":"redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/3df0bdaff167c479390d8c1d9ba8338511cc6ea40b290cd3d84683663005fd1c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3df0bdaff167c479390d8c1d9ba8338511cc6ea40b290cd3d84683663005fd1c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3df0bdaff167c479390d8c1d9ba8338511cc6ea40b290cd3d84683663005fd1c?s=96&d=mm&r=g","caption":"redazione"},"url":"https:\/\/fedic.it\/magazine\/author\/redazione\/"}]}},"jetpack_featured_media_url":"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2021\/07\/Tecnica-Cinematografica.jpeg","_links":{"self":[{"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/posts\/32","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/comments?post=32"}],"version-history":[{"count":3,"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/posts\/32\/revisions"}],"predecessor-version":[{"id":94,"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/posts\/32\/revisions\/94"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/media\/65"}],"wp:attachment":[{"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/media?parent=32"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/categories?post=32"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/tags?post=32"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}