{"id":1290,"date":"2023-11-06T09:27:25","date_gmt":"2023-11-06T09:27:25","guid":{"rendered":"https:\/\/fedic.it\/magazine\/?p=1290"},"modified":"2023-11-06T09:27:25","modified_gmt":"2023-11-06T09:27:25","slug":"lattrice-elisabetta-mazzullo-a-brescia-per-il-booktrailer-film-festival-le-otto-montagne-al-femminile","status":"publish","type":"post","link":"https:\/\/fedic.it\/magazine\/lattrice-elisabetta-mazzullo-a-brescia-per-il-booktrailer-film-festival-le-otto-montagne-al-femminile\/","title":{"rendered":"L\u2019ATTRICE ELISABETTA MAZZULLO A BRESCIA PER IL BOOKTRAILER FILM FESTIVAL  &#8211; LE OTTO MONTAGNE AL FEMMINILE"},"content":{"rendered":"<p><strong>CINECLUB AGEnda CINEMA DI BFRESCIA<br \/>\n<\/strong><strong>di Laura Forcella Iascone<\/strong><\/p>\n<p>Elisabetta Mazzullo \u00e8 attrice protagonista nel film \u201cLe otto montagne\u201d dei due registi belgi Felix Van Groeningen e Charlotte Vandermeersch. \u00c8 protagonista a pieno titolo, nonostante la forza attoriale di Luca Marinelli e Alessandro Borghi che danno corpo e anima a Pietro e a Bruno, i due personaggi principali del libro omonimo di Paolo Cognetti da cui \u00e8 tratto il film. Lei, Elisabetta, interpreta Lara, giovane donna sedotta dalla vita sobria ed essenziale della montagna, prima compagna di Pietro e poi moglie di Bruno. Il film, come il libro, \u00e8 una storia principalmente di uomini, dei loro vissuti spesso silenziosi e del loro rincorrersi ruvido e anche conflittuale. Elisabetta vi si insinua con una vibrazione di inquietudine femminile per le sue malinconiche accensioni di entusiasmo, le sue arrabbiature nei confronti di un marito ancorato graniticamente a un sogno che si rivela impossibile, la sua amicizia per l\u2019ex compagno con cui condivide, in fin dei conti, l\u2019amore preoccupato per Bruno.<\/p>\n<figure id=\"attachment_1273\" aria-describedby=\"caption-attachment-1273\" style=\"width: 708px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1273\" src=\"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2023\/11\/Elisabetta-Mazzullo-con-il-pubblico-al-Liceo-Calini.png\" alt=\"\" width=\"708\" height=\"531\" srcset=\"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2023\/11\/Elisabetta-Mazzullo-con-il-pubblico-al-Liceo-Calini.png 708w, https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2023\/11\/Elisabetta-Mazzullo-con-il-pubblico-al-Liceo-Calini-300x225.png 300w\" sizes=\"auto, (max-width: 708px) 100vw, 708px\" \/><figcaption id=\"caption-attachment-1273\" class=\"wp-caption-text\">Elisabetta Mazzullo con il pubblico al Liceo Calini<\/figcaption><\/figure>\n<p>Elisabetta-Lara \u00e8 stata ospite, grazie ai contattai di Paolo Micalizzi della Fedic, al liceo scientifico Calini di Brescia in un\u2019aula magna, gremita di studenti provenienti anche da altre scuole della citt\u00e0, l\u2019 11 ottobre scorso in un incontro dal titolo, non a caso, \u201cLe otto montagne al femminile\u201d.<\/p>\n<p>L\u2019ha invitata il Booktrailer Film Festival, il progetto europeo del Liceo alla sua XVII edizione che mette al centro l\u2019alleanza tra cinema e letteratura: sono gli studenti, con i loro booktrailer cinematografici, a promuovere i libri che amano.<\/p>\n<p><em>Le otto montagne<\/em> \u00e8 stato uno di questi, oggetto di uno specialissimo laboratorio on line e in inglese che lo scorso anno scolastico ha impegnato studenti e studentesse delle scuole partner europee e che ha generato un booktrailer che porta traccia di sei Paesi diversi in cui \u00e8 stato girato: il booktrailer dell\u2019amicizia, come lo abbiamo definito, \u00e8 stato proiettato alla serata di premiazione della XVI edizione lo scorso 27 marzo e apprezzato dallo stesso Paolo Cognetti che ha inviato un video di saluto.<\/p>\n<figure id=\"attachment_1272\" aria-describedby=\"caption-attachment-1272\" style=\"width: 758px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1272\" src=\"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2023\/11\/Elisabetta-Mazzullo-con-le-intervistatrici.png\" alt=\"\" width=\"758\" height=\"568\" srcset=\"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2023\/11\/Elisabetta-Mazzullo-con-le-intervistatrici.png 758w, https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2023\/11\/Elisabetta-Mazzullo-con-le-intervistatrici-300x225.png 300w\" sizes=\"auto, (max-width: 758px) 100vw, 758px\" \/><figcaption id=\"caption-attachment-1272\" class=\"wp-caption-text\">Elisabetta Mazzullo con le intervistatrici<\/figcaption><\/figure>\n<p>E di amicizia e in amicizia si \u00e8 parlato con Elisabetta Mazzullo, intervistata da due studentesse del Liceo Calini, Margherita Cirelli e Matilde Martire, con domande relative alla sua esperienza cinematografica che ha preso avvio dal teatro e dalla musica, alle sue relazioni sul set, alle difficolt\u00e0 di ripresa nell\u2019ambiente impervio della montagna, alla musica del film, al significato del titolo e alle sue allusioni alla cultura orientale.<\/p>\n<p>Ma non ci sono state solo parole: bellissime immagini sono state condivise da Elisabetta Mazzullo e proiettate in aula magna. Foto del backstage e piccole clip del film commentate hanno ricreato l\u2019atmosfera del set consentendo di approfondire le dinamiche psicologiche tra i personaggi senza fare spoiler del libro e del film.<\/p>\n<p>Alla fine dell\u2019incontro l\u2019invito \u00e8 stato alla lettura del libro e alla visione del film. Elisabetta ha acceso la scintilla del desiderio di leggere e di vedere che, a ben vedere, producono lo stesso effetto: attraverso le storie degli altri capire meglio le proprie.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CINECLUB AGEnda CINEMA DI BFRESCIA di Laura Forcella Iascone Elisabetta Mazzullo \u00e8 attrice protagonista nel film \u201cLe otto montagne\u201d dei due registi belgi Felix Van Groeningen e Charlotte Vandermeersch. \u00c8 protagonista a pieno titolo, nonostante la forza attoriale di Luca Marinelli e Alessandro Borghi che danno corpo e anima a Pietro e a Bruno, i [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[37],"class_list":["post-1290","post","type-post","status-publish","format-standard","hentry","category-fedic","tag-fedic-magazine-46"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019ATTRICE ELISABETTA MAZZULLO A BRESCIA PER IL BOOKTRAILER FILM FESTIVAL - LE OTTO MONTAGNE AL FEMMINILE - Fedic Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fedic.it\/magazine\/lattrice-elisabetta-mazzullo-a-brescia-per-il-booktrailer-film-festival-le-otto-montagne-al-femminile\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019ATTRICE ELISABETTA MAZZULLO A BRESCIA PER IL BOOKTRAILER FILM FESTIVAL - LE OTTO MONTAGNE AL FEMMINILE - Fedic Magazine\" \/>\n<meta property=\"og:description\" content=\"CINECLUB AGEnda CINEMA DI BFRESCIA di Laura Forcella Iascone Elisabetta Mazzullo \u00e8 attrice protagonista nel film \u201cLe otto montagne\u201d dei due registi belgi Felix Van Groeningen e Charlotte Vandermeersch. \u00c8 protagonista a pieno titolo, nonostante la forza attoriale di Luca Marinelli e Alessandro Borghi che danno corpo e anima a Pietro e a Bruno, i [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fedic.it\/magazine\/lattrice-elisabetta-mazzullo-a-brescia-per-il-booktrailer-film-festival-le-otto-montagne-al-femminile\/\" \/>\n<meta property=\"og:site_name\" content=\"Fedic Magazine\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-06T09:27:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2023\/11\/Elisabetta-Mazzullo-con-il-pubblico-al-Liceo-Calini.png\" \/>\n<meta name=\"author\" content=\"redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/lattrice-elisabetta-mazzullo-a-brescia-per-il-booktrailer-film-festival-le-otto-montagne-al-femminile\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/lattrice-elisabetta-mazzullo-a-brescia-per-il-booktrailer-film-festival-le-otto-montagne-al-femminile\\\/\"},\"author\":{\"name\":\"redazione\",\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/#\\\/schema\\\/person\\\/49d2a224aa980c875e12fa73c5601332\"},\"headline\":\"L\u2019ATTRICE ELISABETTA MAZZULLO A BRESCIA PER IL BOOKTRAILER FILM FESTIVAL &#8211; LE OTTO MONTAGNE AL FEMMINILE\",\"datePublished\":\"2023-11-06T09:27:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/lattrice-elisabetta-mazzullo-a-brescia-per-il-booktrailer-film-festival-le-otto-montagne-al-femminile\\\/\"},\"wordCount\":543,\"publisher\":{\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/lattrice-elisabetta-mazzullo-a-brescia-per-il-booktrailer-film-festival-le-otto-montagne-al-femminile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Elisabetta-Mazzullo-con-il-pubblico-al-Liceo-Calini.png\",\"keywords\":[\"FEDIC Magazine 46\"],\"articleSection\":[\"Fedic\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/lattrice-elisabetta-mazzullo-a-brescia-per-il-booktrailer-film-festival-le-otto-montagne-al-femminile\\\/\",\"url\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/lattrice-elisabetta-mazzullo-a-brescia-per-il-booktrailer-film-festival-le-otto-montagne-al-femminile\\\/\",\"name\":\"L\u2019ATTRICE ELISABETTA MAZZULLO A BRESCIA PER IL BOOKTRAILER FILM FESTIVAL - LE OTTO MONTAGNE AL FEMMINILE - Fedic Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/lattrice-elisabetta-mazzullo-a-brescia-per-il-booktrailer-film-festival-le-otto-montagne-al-femminile\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/lattrice-elisabetta-mazzullo-a-brescia-per-il-booktrailer-film-festival-le-otto-montagne-al-femminile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Elisabetta-Mazzullo-con-il-pubblico-al-Liceo-Calini.png\",\"datePublished\":\"2023-11-06T09:27:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/lattrice-elisabetta-mazzullo-a-brescia-per-il-booktrailer-film-festival-le-otto-montagne-al-femminile\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fedic.it\\\/magazine\\\/lattrice-elisabetta-mazzullo-a-brescia-per-il-booktrailer-film-festival-le-otto-montagne-al-femminile\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/lattrice-elisabetta-mazzullo-a-brescia-per-il-booktrailer-film-festival-le-otto-montagne-al-femminile\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Elisabetta-Mazzullo-con-il-pubblico-al-Liceo-Calini.png\",\"contentUrl\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Elisabetta-Mazzullo-con-il-pubblico-al-Liceo-Calini.png\",\"width\":708,\"height\":531,\"caption\":\"Elisabetta Mazzullo con il pubblico al Liceo Calini\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/lattrice-elisabetta-mazzullo-a-brescia-per-il-booktrailer-film-festival-le-otto-montagne-al-femminile\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019ATTRICE ELISABETTA MAZZULLO A BRESCIA PER IL BOOKTRAILER FILM FESTIVAL &#8211; LE OTTO MONTAGNE AL FEMMINILE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/#website\",\"url\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/\",\"name\":\"Fedic Magazine\",\"description\":\"Il blog della Federazione Italiana dei Cineclub\",\"publisher\":{\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/#organization\",\"name\":\"Fedic Magazine\",\"url\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo-fedic-magazine-ok.jpg\",\"contentUrl\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo-fedic-magazine-ok.jpg\",\"width\":405,\"height\":110,\"caption\":\"Fedic Magazine\"},\"image\":{\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/#\\\/schema\\\/person\\\/49d2a224aa980c875e12fa73c5601332\",\"name\":\"redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3df0bdaff167c479390d8c1d9ba8338511cc6ea40b290cd3d84683663005fd1c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3df0bdaff167c479390d8c1d9ba8338511cc6ea40b290cd3d84683663005fd1c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3df0bdaff167c479390d8c1d9ba8338511cc6ea40b290cd3d84683663005fd1c?s=96&d=mm&r=g\",\"caption\":\"redazione\"},\"url\":\"https:\\\/\\\/fedic.it\\\/magazine\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019ATTRICE ELISABETTA MAZZULLO A BRESCIA PER IL BOOKTRAILER FILM FESTIVAL - LE OTTO MONTAGNE AL FEMMINILE - Fedic Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fedic.it\/magazine\/lattrice-elisabetta-mazzullo-a-brescia-per-il-booktrailer-film-festival-le-otto-montagne-al-femminile\/","og_locale":"it_IT","og_type":"article","og_title":"L\u2019ATTRICE ELISABETTA MAZZULLO A BRESCIA PER IL BOOKTRAILER FILM FESTIVAL - LE OTTO MONTAGNE AL FEMMINILE - Fedic Magazine","og_description":"CINECLUB AGEnda CINEMA DI BFRESCIA di Laura Forcella Iascone Elisabetta Mazzullo \u00e8 attrice protagonista nel film \u201cLe otto montagne\u201d dei due registi belgi Felix Van Groeningen e Charlotte Vandermeersch. \u00c8 protagonista a pieno titolo, nonostante la forza attoriale di Luca Marinelli e Alessandro Borghi che danno corpo e anima a Pietro e a Bruno, i [&hellip;]","og_url":"https:\/\/fedic.it\/magazine\/lattrice-elisabetta-mazzullo-a-brescia-per-il-booktrailer-film-festival-le-otto-montagne-al-femminile\/","og_site_name":"Fedic Magazine","article_published_time":"2023-11-06T09:27:25+00:00","og_image":[{"url":"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2023\/11\/Elisabetta-Mazzullo-con-il-pubblico-al-Liceo-Calini.png","type":"","width":"","height":""}],"author":"redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fedic.it\/magazine\/lattrice-elisabetta-mazzullo-a-brescia-per-il-booktrailer-film-festival-le-otto-montagne-al-femminile\/#article","isPartOf":{"@id":"https:\/\/fedic.it\/magazine\/lattrice-elisabetta-mazzullo-a-brescia-per-il-booktrailer-film-festival-le-otto-montagne-al-femminile\/"},"author":{"name":"redazione","@id":"https:\/\/fedic.it\/magazine\/#\/schema\/person\/49d2a224aa980c875e12fa73c5601332"},"headline":"L\u2019ATTRICE ELISABETTA MAZZULLO A BRESCIA PER IL BOOKTRAILER FILM FESTIVAL &#8211; LE OTTO MONTAGNE AL FEMMINILE","datePublished":"2023-11-06T09:27:25+00:00","mainEntityOfPage":{"@id":"https:\/\/fedic.it\/magazine\/lattrice-elisabetta-mazzullo-a-brescia-per-il-booktrailer-film-festival-le-otto-montagne-al-femminile\/"},"wordCount":543,"publisher":{"@id":"https:\/\/fedic.it\/magazine\/#organization"},"image":{"@id":"https:\/\/fedic.it\/magazine\/lattrice-elisabetta-mazzullo-a-brescia-per-il-booktrailer-film-festival-le-otto-montagne-al-femminile\/#primaryimage"},"thumbnailUrl":"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2023\/11\/Elisabetta-Mazzullo-con-il-pubblico-al-Liceo-Calini.png","keywords":["FEDIC Magazine 46"],"articleSection":["Fedic"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/fedic.it\/magazine\/lattrice-elisabetta-mazzullo-a-brescia-per-il-booktrailer-film-festival-le-otto-montagne-al-femminile\/","url":"https:\/\/fedic.it\/magazine\/lattrice-elisabetta-mazzullo-a-brescia-per-il-booktrailer-film-festival-le-otto-montagne-al-femminile\/","name":"L\u2019ATTRICE ELISABETTA MAZZULLO A BRESCIA PER IL BOOKTRAILER FILM FESTIVAL - LE OTTO MONTAGNE AL FEMMINILE - Fedic Magazine","isPartOf":{"@id":"https:\/\/fedic.it\/magazine\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fedic.it\/magazine\/lattrice-elisabetta-mazzullo-a-brescia-per-il-booktrailer-film-festival-le-otto-montagne-al-femminile\/#primaryimage"},"image":{"@id":"https:\/\/fedic.it\/magazine\/lattrice-elisabetta-mazzullo-a-brescia-per-il-booktrailer-film-festival-le-otto-montagne-al-femminile\/#primaryimage"},"thumbnailUrl":"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2023\/11\/Elisabetta-Mazzullo-con-il-pubblico-al-Liceo-Calini.png","datePublished":"2023-11-06T09:27:25+00:00","breadcrumb":{"@id":"https:\/\/fedic.it\/magazine\/lattrice-elisabetta-mazzullo-a-brescia-per-il-booktrailer-film-festival-le-otto-montagne-al-femminile\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fedic.it\/magazine\/lattrice-elisabetta-mazzullo-a-brescia-per-il-booktrailer-film-festival-le-otto-montagne-al-femminile\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/fedic.it\/magazine\/lattrice-elisabetta-mazzullo-a-brescia-per-il-booktrailer-film-festival-le-otto-montagne-al-femminile\/#primaryimage","url":"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2023\/11\/Elisabetta-Mazzullo-con-il-pubblico-al-Liceo-Calini.png","contentUrl":"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2023\/11\/Elisabetta-Mazzullo-con-il-pubblico-al-Liceo-Calini.png","width":708,"height":531,"caption":"Elisabetta Mazzullo con il pubblico al Liceo Calini"},{"@type":"BreadcrumbList","@id":"https:\/\/fedic.it\/magazine\/lattrice-elisabetta-mazzullo-a-brescia-per-il-booktrailer-film-festival-le-otto-montagne-al-femminile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fedic.it\/magazine\/"},{"@type":"ListItem","position":2,"name":"L\u2019ATTRICE ELISABETTA MAZZULLO A BRESCIA PER IL BOOKTRAILER FILM FESTIVAL &#8211; LE OTTO MONTAGNE AL FEMMINILE"}]},{"@type":"WebSite","@id":"https:\/\/fedic.it\/magazine\/#website","url":"https:\/\/fedic.it\/magazine\/","name":"Fedic Magazine","description":"Il blog della Federazione Italiana dei Cineclub","publisher":{"@id":"https:\/\/fedic.it\/magazine\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fedic.it\/magazine\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/fedic.it\/magazine\/#organization","name":"Fedic Magazine","url":"https:\/\/fedic.it\/magazine\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/fedic.it\/magazine\/#\/schema\/logo\/image\/","url":"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2021\/07\/logo-fedic-magazine-ok.jpg","contentUrl":"https:\/\/fedic.it\/magazine\/wp-content\/uploads\/2021\/07\/logo-fedic-magazine-ok.jpg","width":405,"height":110,"caption":"Fedic Magazine"},"image":{"@id":"https:\/\/fedic.it\/magazine\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/fedic.it\/magazine\/#\/schema\/person\/49d2a224aa980c875e12fa73c5601332","name":"redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/3df0bdaff167c479390d8c1d9ba8338511cc6ea40b290cd3d84683663005fd1c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3df0bdaff167c479390d8c1d9ba8338511cc6ea40b290cd3d84683663005fd1c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3df0bdaff167c479390d8c1d9ba8338511cc6ea40b290cd3d84683663005fd1c?s=96&d=mm&r=g","caption":"redazione"},"url":"https:\/\/fedic.it\/magazine\/author\/redazione\/"}]}},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/posts\/1290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/comments?post=1290"}],"version-history":[{"count":1,"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/posts\/1290\/revisions"}],"predecessor-version":[{"id":1291,"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/posts\/1290\/revisions\/1291"}],"wp:attachment":[{"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/media?parent=1290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/categories?post=1290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fedic.it\/magazine\/wp-json\/wp\/v2\/tags?post=1290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}